{"id":24171,"date":"2025-10-11T10:04:55","date_gmt":"2025-10-11T08:04:55","guid":{"rendered":"https:\/\/ismfrance.org\/?p=24171"},"modified":"2025-10-11T10:04:55","modified_gmt":"2025-10-11T08:04:55","slug":"le-grand-israel-pour-les-nuls","status":"publish","type":"post","link":"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/","title":{"rendered":"Le Grand Isra\u00ebl pour les Nuls"},"content":{"rendered":"<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\"><strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/x.com\/HandalaFreedom\">Handala<\/a><\/span>, 10 octobre 2025.<\/strong> Le 12 ao\u00fbt 2025, le Premier ministre isra\u00e9lien Benjamin Netanyahou (Benjamin Mileikowsky) a publiquement soutenu le projet de \u00ab\u00a0Grand Isra\u00ebl\u00a0\u00bb, <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.timesofisrael.com\/liveblog_entry\/netanyahu-says-hes-on-a-historic-and-spiritual-mission-endorses-vision-of-greater-israel\/\">d\u00e9clarant<\/a> <\/span>dans une interview \u00e0 <i>i24 News<\/i> qu&rsquo;il entreprenait une \u00ab\u00a0<i>mission historique et spirituelle\u00a0<\/i>\u00bb de conqu\u00eate territoriale.<\/span><\/span><\/span><\/p>\n<p><a href=\"https:\/\/ismfrance.org\/wp-content\/uploads\/2025\/10\/greaterisrael.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-24175 aligncenter\" src=\"https:\/\/ismfrance.org\/wp-content\/uploads\/2025\/10\/greaterisrael.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/ismfrance.org\/wp-content\/uploads\/2025\/10\/greaterisrael.jpg 640w, https:\/\/ismfrance.org\/wp-content\/uploads\/2025\/10\/greaterisrael-300x225.jpg 300w, https:\/\/ismfrance.org\/wp-content\/uploads\/2025\/10\/greaterisrael-350x263.jpg 350w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Cette id\u00e9ologie expansive \u00e9tend le cadre historique du Grand Isra\u00ebl, qui exerce d\u00e9j\u00e0 une autorit\u00e9 coloniale sur J\u00e9rusalem-Est, le plateau du Golan, la Cisjordanie et, une fois de plus, Gaza \u2013 dont les dirigeants isra\u00e9liens souhaitent ardemment reprendre le contr\u00f4le. L&rsquo;objectif est d&rsquo;\u00e9tendre les colonies juives \u00e0 l&rsquo;ensemble de la Palestine historique, que les sionistes pr\u00e9tendent avoir \u00e9t\u00e9 habit\u00e9e uniquement par les anciens H\u00e9breux et octroy\u00e9e par le Dieu juif au \u00ab\u00a0peuple \u00e9lu\u00a0\u00bb, ainsi qu&rsquo;aux nations arabes adjacentes comme la Jordanie, l&rsquo;\u00c9gypte, la Syrie et le Liban.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Le soutien \u00e0 cette id\u00e9ologie s&rsquo;est intensifi\u00e9 pendant le g\u00e9nocide isra\u00e9lien \u00e0 Gaza, avec des photos virales montrant des soldats isra\u00e9liens portant sur leurs uniformes des \u00e9cussons repr\u00e9sentant une carte du Grand Isra\u00ebl.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Parall\u00e8lement, le gouvernement isra\u00e9lien intensifie ses efforts pour consolider ses revendications territoriales. En ao\u00fbt 2025, il a approuv\u00e9 une s\u00e9rie de plans, dont celui visant \u00e0 prendre le contr\u00f4le de Gaza-ville et du projet de colonie E1 en Cisjordanie. Cette mesure couperait l&rsquo;acc\u00e8s des Palestiniens \u00e0 J\u00e9rusalem-Est, d\u00e9racinerait les communaut\u00e9s b\u00e9douines locales et, comme l&rsquo;ont d\u00e9clar\u00e9 de hauts responsables, \u00ab<i>\u00a0enterrerait d\u00e9finitivement l&rsquo;id\u00e9e d&rsquo;un \u00c9tat palestinien<\/i>\u00a0\u00bb.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Alors qu&rsquo;Isra\u00ebl affiche fi\u00e8rement son expansionnisme violent, marqu\u00e9 par des massacres et la famine d\u00e9lib\u00e9r\u00e9e inflig\u00e9e \u00e0 des millions de personnes, ses partisans sont pass\u00e9s \u00e0 l&rsquo;offensive, pr\u00e9sentant les op\u00e9rations men\u00e9es depuis octobre 2023 comme une simple \u00ab<i>\u00a0l\u00e9gitime d\u00e9fense\u00a0<\/i>\u00bb plut\u00f4t que comme le point final d&rsquo;une longue histoire de colonialisme de peuplement et d&rsquo;apartheid syst\u00e9mique. Fid\u00e8les \u00e0 leur tradition sioniste, les groupes pro-isra\u00e9liens ont lanc\u00e9 une vaste campagne de propagande de d\u00e9formation des faits\u00a0: ils pr\u00e9sentent les Isra\u00e9liens \u00e0 la fois comme des victimes des Palestiniens et comme des habitants \u00ab autochtones \u00bb l\u00e9gitimes qui reprennent leur patrie \u00ab juive \u00bb ancestrale \u00e0 ceux qu&rsquo;ils qualifient de \u00ab colons \u00bb palestiniens.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Pour entretenir ce mythe, ils ont d\u00fb blanchir les racines coloniales du sionisme, moteur principal de l&rsquo;oppression persistante des Palestiniens par Isra\u00ebl.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Au d\u00e9but, le mouvement sioniste a ouvertement qualifi\u00e9 ses activit\u00e9s de \u00ab coloniales \u00bb et de \u00ab colonisation \u00bb en cr\u00e9ant des entit\u00e9s comme le \u00ab Jewish Colonial Trust \u00bb et l&rsquo;\u00ab Association juive de colonisation de Palestine \u00bb, pour ensuite abandonner cette terminologie lorsque \u00ab <i>colonisation<\/i> \u00bb est devenue synonyme d&rsquo;imp\u00e9rialisme et d&rsquo;exploitation.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">\u00c0 partir des ann\u00e9es 1930, ils ont modifi\u00e9 leur rh\u00e9torique, abandonnant le terme mais intensifiant ses pratiques sous-jacentes avec une f\u00e9rocit\u00e9 accrue.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Bien que cette campagne de distorsion id\u00e9ologique remonte bien avant l&rsquo;attaque g\u00e9nocidaire d&rsquo;Isra\u00ebl contre Gaza, ses architectes l&rsquo;ont consid\u00e9rablement amplifi\u00e9e pour rationaliser le massacre incessant qui s&rsquo;y d\u00e9roule.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Prenons par exemple la fiche d&rsquo;information publi\u00e9e l&rsquo;ann\u00e9e derni\u00e8re par l&rsquo;American Jewish Committee, intitul\u00e9e \u00ab<i>\u00a0R\u00e9pondre aux fausses all\u00e9gations concernant Isra\u00ebl\u00a0<\/i>\u00bb. Elle tente de d\u00e9manteler l&rsquo;applicabilit\u00e9 du colonialisme de peuplement inflig\u00e9 aux Palestiniens par le projet sioniste et Isra\u00ebl.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Elle <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.ajc.org\/why-israel-is-not-a-settler-colonial-state\">affirme<\/a> <\/span>que le colonialisme de peuplement\u00a0:<\/span><\/span><\/span><\/p>\n<blockquote><p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">\u00ab\u00a0d\u00e9signe la tentative d&rsquo;une puissance imp\u00e9riale de remplacer la population autochtone d&rsquo;un territoire par une nouvelle soci\u00e9t\u00e9 de colons.\u00a0\u00bb <\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">\u00ab\u00a0Il ne peut d\u00e9crire une r\u00e9alit\u00e9 dans laquelle un groupe national, agissant en son nom et non sur ordre d&rsquo;une puissance ext\u00e9rieure, retourne sur sa terre natale historique pour obtenir l&rsquo;autod\u00e9termination tout en soutenant la cr\u00e9ation d&rsquo;un \u00c9tat-nation pour un autre groupe national, parall\u00e8lement \u00e0 la cr\u00e9ation de son propre \u00c9tat.\u00bb<\/span><\/span><\/span><\/p><\/blockquote>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Tr\u00e8s bien, examinons ces deux points principaux.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Nombre d&rsquo;initiatives coloniales europ\u00e9ennes s&rsquo;appuyaient fortement sur le mythe du \u00ab retour \u00bb \u00e0 de pr\u00e9tendues terres ancestrales.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Les Fran\u00e7ais, par exemple, ont pr\u00e9sent\u00e9 leur colonisation de l&rsquo;Alg\u00e9rie comme une l\u00e9gitime reconqu\u00eate des terres de l&rsquo;Empire romain, se positionnant comme les v\u00e9ritables h\u00e9ritiers et d\u00e9signant les Arabes alg\u00e9riens autochtones comme les colons.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">De m\u00eame, les Italiens ont justifi\u00e9 leur prise de contr\u00f4le brutale de la Libye en invoquant un \u00ab retour \u00bb \u00e0 la grandeur de la Rome antique, transformant leur colonisation en une noble renaissance d&rsquo;un h\u00e9ritage perdu.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Les nazis allemands, eux aussi, ont pr\u00e9sent\u00e9 leur expansion en Europe de l&rsquo;Est et dans les territoires sovi\u00e9tiques comme un grand \u00ab retour \u00bb. Ils affirmaient que ces r\u00e9gions \u00e9taient intrins\u00e8quement li\u00e9es \u00e0 l&rsquo;identit\u00e9 allemande, des terres o\u00f9 le Volk ne faisait que revenir. Hitler lui-m\u00eame l&rsquo;a clairement exprim\u00e9 en d\u00e9clarant :<\/span><\/span><\/span><\/p>\n<blockquote><p><em><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">\u00ab<\/span><\/span><\/span><\/em> <span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Mes objectifs ne sont pas d\u00e9mesur\u00e9s ; fondamentalement, ce sont toutes des r\u00e9gions o\u00f9 des Allemands \u00e9taient auparavant install\u00e9s. Le Volk allemand doit s&rsquo;y d\u00e9velopper. <\/span><\/span><\/span><em><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">\u00bb <\/span><\/span><\/span><\/em><\/p><\/blockquote>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Au-del\u00e0 de cela, l&rsquo;id\u00e9ologie nazie visait le \u00ab retour \u00bb sur les territoires du Premier Reich, ou Saint-Empire romain germanique, englobant des parties de la Russie, de la Pologne, de l&rsquo;Ukraine, de la Bi\u00e9lorussie, des \u00c9tats baltes, etc.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Dans ce contexte, l&rsquo;affirmation sioniste selon laquelle les juifs europ\u00e9ens ne faisaient que \u00ab retourner \u00bb dans une \u00ab ancienne patrie \u00bb en Palestine s&rsquo;inscrit parfaitement dans ces sombres pr\u00e9c\u00e9dents de l&rsquo;histoire coloniale europ\u00e9enne.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">L&rsquo;autre argument selon lequel les colons rejettent intrins\u00e8quement \u00ab <i>la cr\u00e9ation d&rsquo;un \u00c9tat-nation pour un autre groupe national, parall\u00e8lement \u00e0 la cr\u00e9ation de leur propre \u00c9tat<\/i> \u00bb, est \u00e9galement faux.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Prenons l&rsquo;exemple du r\u00e9gime sud-africain blanc de l&rsquo;apartheid, qui a cr\u00e9\u00e9 dix bantoustans soi-disant \u00ab ind\u00e9pendants \u00bb pour priver la majorit\u00e9 noire autochtone de sa citoyennet\u00e9, tout en enracinant la supr\u00e9matie blanche. Durant leur occupation de la Namibie, ils ont \u00e9tendu cette tactique en cr\u00e9ant des bantoustans pour les Namibiens autochtones afin de perp\u00e9tuer la supr\u00e9matie blanche.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Faisant \u00e9cho aux Fran\u00e7ais, aux Italiens et aux Allemands dans leurs logiques coloniales, les sionistes ont depuis longtemps invers\u00e9 le r\u00e9cit, insistant sur le fait que les Palestiniens \u2013 v\u00e9ritables gardiens autochtones de la terre \u2013 sont les v\u00e9ritables \u00ab colons \u00bb de ce qu&rsquo;ils consid\u00e8rent comme l&rsquo;\u00ab ancienne patrie \u00bb des Juifs europ\u00e9ens, en faisant simplement remonter les racines palestiniennes aux seuls conqu\u00e9rants arabes musulmans de Palestine et de Syrie au VIIe si\u00e8cle.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Pourtant, l&rsquo;expansion arabe \u00e9tait loin d&rsquo;\u00eatre un colonialisme de peuplement\u00a0; elle \u00e9tait motiv\u00e9e par le pros\u00e9lytisme religieux et l&rsquo;ambition territoriale, sans d\u00e9placement ni expulsion des autochtones.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">La grande majorit\u00e9 des habitants autochtones de Palestine et de Syrie, longtemps gouvern\u00e9s par l&rsquo;Empire byzantin avant de tomber sous contr\u00f4le arabo-musulman, ont continu\u00e9 de dominer le paysage d\u00e9mographique apr\u00e8s la conqu\u00eate, un groupe qui comprenait notamment les Ghassanides chr\u00e9tiens arabophones syriens.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Il a fallu environ cinq si\u00e8cles en Palestine et en Grande Syrie \u2013 et une p\u00e9riode encore plus longue en \u00c9gypte \u2013 avant que la majorit\u00e9 ne se convertisse \u00e0 l&rsquo;islam, mais l&rsquo;arabisation et l&rsquo;adoption de la langue arabe ont eu lieu bien plus t\u00f4t, y compris dans les \u00e9glises chr\u00e9tiennes autochtones.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Seul un petit nombre d&rsquo;Arabes se sont install\u00e9s dans les r\u00e9gions conquises, et les rares qui l&rsquo;ont fait ont fini par s&rsquo;installer dans les villes.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Lorsque les Croisades \u2013 que je consid\u00e8re comme les premiers v\u00e9ritables sionistes \u2013 ont envahi la Palestine au XIe si\u00e8cle, la population de la r\u00e9gion \u00e9tait principalement compos\u00e9e de chr\u00e9tiens arabophones, accompagn\u00e9s d&rsquo;une minorit\u00e9 de musulmans arabophones.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Encore en 1919, des personnalit\u00e9s comme David Ben Gourion (n\u00e9 David Gr\u00fcn) et Yitzhak Ben-Zvi (n\u00e9 Izaak Shimshelevich), architectes essentiels de la colonisation juive, affirmaient dans un ouvrage \u00e9crit conjointement que la grande majorit\u00e9 des Palestiniens de souche remontaient aux anciens H\u00e9breux, apr\u00e8s s&rsquo;\u00eatre convertis au christianisme puis \u00e0 l&rsquo;islam.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">En confondant l&rsquo;identit\u00e9 arabe avec une construction raciale au lieu de la reconna\u00eetre comme une identit\u00e9 linguistique et culturelle partag\u00e9e, les puissances imp\u00e9riales europ\u00e9ennes racialis\u00e9es cherchaient \u00e0 briser l&rsquo;unit\u00e9 arabe. Elles pr\u00e9tendaient que les \u00c9gyptiens, les Irakiens, les Nord-Africains, les Maronites et d&rsquo;autres n&rsquo;avaient pas de v\u00e9ritables racines arabes, les pr\u00e9sentant comme de simples peuples conquis, simplement assimil\u00e9s par arabisation. Pourtant, le nationalisme arabe maintenait fermement que les Arabes englobaient tous ceux pour qui l&rsquo;arabe \u00e9tait la langue maternelle, rejetant toute id\u00e9e que l&rsquo;arabit\u00e9 constituait une cat\u00e9gorie raciale ou ethnique. Un autre argument sioniste r\u00e9pandu est que la Grande-Bretagne n&rsquo;a pas jou\u00e9 le r\u00f4le de \u00ab m\u00e8re patrie \u00bb ou de \u00ab m\u00e9tropole \u00bb pour les colons sionistes, la plupart des arrivants \u00e9tant originaires de diverses nations europ\u00e9ennes et non de citoyens britanniques. Ce raisonnement est cependant incomplet.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">En r\u00e9alit\u00e9, la colonisation de la Palestine refl\u00e9tait les projets europ\u00e9ens classiques. Le soutien britannique \u00e0 la colonisation sioniste \u2013 incluant des Juifs d&rsquo;Europe et de Grande-Bretagne \u2013 n&rsquo;\u00e9tait pas un cas isol\u00e9. Auparavant, la Grande-Bretagne avait orchestr\u00e9 la colonisation de l&rsquo;Irlande par des huguenots britanniques, allemands et fran\u00e7ais, m\u00eame si la majorit\u00e9 de ces colons \u00e9taient \u00e9cossais et anglais.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">De m\u00eame, les N\u00e9erlandais ont colonis\u00e9 l&rsquo;Afrique australe avec leurs propres populations, aux c\u00f4t\u00e9s des huguenots fran\u00e7ais, o\u00f9 les N\u00e9erlandais \u00e9taient majoritaires. Les Fran\u00e7ais, \u00e0 leur tour, ont \u00e9tabli des colonies en Afrique du Nord, principalement avec leurs propres citoyens, tout en faisant venir des Espagnols, des Italiens, des Suisses, des Maltais et des Russes. Ce mod\u00e8le a perdur\u00e9 lors de la colonisation de peuplement de la Russie tsariste sur les terres ottomanes conquises par Catherine la Grande vers la fin du XVIIIe si\u00e8cle, attirant des Juifs polonais, des Bulgares, des Italiens, des Allemands, des Grecs, des Roumains et de nombreux autres \u00e0 se joindre \u00e0 ce projet colonial.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Plus d&rsquo;un si\u00e8cle plus tard, en 1897, la colonie russe d&rsquo;Odessa conservait une majorit\u00e9 d\u00e9mographique de Juifs, de Grecs, d&rsquo;Ukrainiens, de Polonais et d&rsquo;Allemands, les Russes repr\u00e9sentant moins de 49 % de sa population.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">\u00c0 la lumi\u00e8re de ces parall\u00e8les historiques, le soutien britannique aux colons sionistes \u2013 dont une partie \u00e9tait effectivement britannique \u2013 appara\u00eet non pas comme une exception, mais comme un exemple particuli\u00e8rement frappant d&rsquo;un mod\u00e8le colonial europ\u00e9en profond\u00e9ment ancr\u00e9.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Un autre argument pr\u00e9tend que le sionisme se distinguait des entreprises coloniales classiques car il visait l&rsquo;\u00ab autod\u00e9termination \u00bb et la \u00ab lib\u00e9ration nationale \u00bb des juifs \u2013 objectifs g\u00e9n\u00e9ralement associ\u00e9s aux peuples colonis\u00e9s \u2013 et les a r\u00e9alis\u00e9es par le biais du colonialisme de peuplement en Palestine. Cette id\u00e9e est pourtant totalement absurde.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Les colons europ\u00e9ens blancs d&rsquo;Am\u00e9rique du Nord ont \u00e9galement lutt\u00e9 pour l&rsquo;ind\u00e9pendance, l&rsquo;\u00ab autod\u00e9termination \u00bb et la \u00ab lib\u00e9ration nationale \u00bb contre la domination britannique.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Les colons espagnols des territoires qui ont donn\u00e9 naissance \u00e0 l&rsquo;Am\u00e9rique latine poursuivaient des objectifs similaires dans leur lutte contre l&rsquo;Espagne.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Les Boers n\u00e9erlandais d&rsquo;Afrique du Sud ont lanc\u00e9 des guerres contre les colons britanniques pour revendiquer l&rsquo;\u00ab autod\u00e9termination \u00bb des colons, \u00e0 l&rsquo;instar de certains sionistes qui se sont retourn\u00e9s contre la Grande-Bretagne apr\u00e8s 1945 pour obtenir l&rsquo;\u00ab ind\u00e9pendance \u00bb des colonies de peuplement.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Les colons fran\u00e7ais d&rsquo;Alg\u00e9rie sont all\u00e9s jusqu&rsquo;\u00e0 fomenter un coup d&rsquo;\u00c9tat contre la France elle-m\u00eame afin de pr\u00e9server leur implantation coloniale, faisant \u00e9cho aux actions d&rsquo;autres colons \u00e0 travers le monde, comme les Rhod\u00e9siens blancs. En fin de compte, la volont\u00e9 sioniste d&rsquo;\u00e9tablir une entit\u00e9 coloniale de peuplement en Palestine ne pr\u00e9sente aucun trait distinctif qui la distingue de ces parall\u00e8les historiques.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Au c\u0153ur du r\u00e9cit destin\u00e9 aux publics chr\u00e9tiens europ\u00e9ens et am\u00e9ricains se trouve la revendication sioniste d&rsquo;une \u00ab\u00a0indig\u00e9n\u00e9it\u00e9\u00a0\u00bb en Palestine, s&rsquo;appuyant sur des mythes bibliques et, plus r\u00e9cemment, sur de pr\u00e9tendus liens \u00ab\u00a0g\u00e9n\u00e9tiques\u00a0\u00bb. Au c\u0153ur de ce vol sioniste de la patrie ancestrale des Palestiniens se trouvent ces liens bibliques et historiques invent\u00e9s, centr\u00e9s sur l&rsquo;affirmation fondamentale selon laquelle seul le \u00ab\u00a0peuple juif\u00a0\u00bb habitait la Palestine il y a environ deux mille ans.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Or, \u00e0 cette \u00e9poque, seule une partie de la population palestinienne \u00e9tait compos\u00e9e d&rsquo;H\u00e9breux \u2013 et non du \u00ab\u00a0peuple juif\u00a0\u00bb, terme invent\u00e9 bien plus tard \u2013 et ces H\u00e9breux n&rsquo;en furent jamais les seuls habitants.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">En r\u00e9alit\u00e9, le r\u00e9cit biblique lui-m\u00eame, dans le livre de Josu\u00e9, r\u00e9v\u00e8le que les H\u00e9breux sont originaires d&rsquo;ailleurs, envahissant et s&#8217;emparant du pays de Canaan \u00e0 ses autochtones canan\u00e9ens, tout cela sous la banni\u00e8re d&rsquo;une \u00ab\u00a0promesse\u00a0\u00bb divine de leur Dieu. Les \u00c9critures mentionnent m\u00eame qu&rsquo;Abraham, le personnage avec lequel le dieu des H\u00e9breux a conclu une alliance, \u00e9tait originaire d&rsquo;Ur, dans l&rsquo;actuel Irak.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Plus absurde encore est le mythe selon lequel les Juifs d&rsquo;aujourd&rsquo;hui seraient les descendants purs et uniques de ces anciens H\u00e9breux.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Ce mythe s&rsquo;est consolid\u00e9 dans la th\u00e9ologie chr\u00e9tienne, issu de l&rsquo;antagonisme de longue date de l&rsquo;\u00c9glise catholique envers les Juifs europ\u00e9ens, les qualifiant d&rsquo;h\u00e9ritiers des anciens H\u00e9breux consid\u00e9r\u00e9s comme des \u00ab\u00a0assassins du Christ\u00a0\u00bb, et amplifi\u00e9 par les ambitions mill\u00e9naristes de la R\u00e9forme protestante d&rsquo;expulser les Juifs d&rsquo;Europe vers la Palestine dans l&rsquo;espoir d&rsquo;acc\u00e9l\u00e9rer le retour de J\u00e9sus-Christ. Ce n&rsquo;est qu&rsquo;\u00e0 la fin du XVIIIe si\u00e8cle que les chr\u00e9tiens europ\u00e9ens ont commenc\u00e9 \u00e0 consid\u00e9rer les Juifs comme une \u00ab\u00a0nation\u00a0\u00bb \u00e9trang\u00e8re distincte.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">La croyance ancienne de nombreux Juifs religieux selon laquelle leurs origines se trouvent en Palestine est comparable \u00e0 celle des musulmans d&rsquo;Inde, de Chine, d&rsquo;Indon\u00e9sie, du Nig\u00e9ria ou de Malaisie qui affirment \u00eatre venus d&rsquo;Arabie, uniquement parce que l&rsquo;Arabie \u00e9tait le berceau de leur religion.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Cela refl\u00e9terait l&rsquo;absurdit\u00e9 de ces musulmans revendiquant un droit \u00ab indiscutable \u00bb sur La Mecque et l&rsquo;Arabie, ou insistant sur une \u00ab pr\u00e9sence ininterrompue \u00bb dans ces r\u00e9gions simplement parce que quelques p\u00e8lerins dispers\u00e9s de leurs terres s&rsquo;y sont install\u00e9s au fil du temps, ou parce qu&rsquo;une poign\u00e9e d&rsquo;Arabes musulmans ont migr\u00e9 vers ces r\u00e9gions lointaines d&rsquo;Asie ou d&rsquo;Afrique \u00e0 la m\u00eame p\u00e9riode.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Les sionistes rejettent ces comparaisons en arguant que le juda\u00efsme n&rsquo;a jamais \u00e9t\u00e9 une religion missionnaire, mais l&rsquo;histoire prouve le contraire\u00a0: les sp\u00e9cialistes ont d\u00e9montr\u00e9 sans l&rsquo;ombre d&rsquo;un doute que le juda\u00efsme a vigoureusement recherch\u00e9 des conversions, des conversions massives ayant persist\u00e9 au moins jusqu&rsquo;au IXe si\u00e8cle.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">M\u00eame en admettant l&rsquo;id\u00e9e d&rsquo;un \u00ab\u00a0lien\u00a0\u00bb entre les Juifs europ\u00e9ens et la Palestine \u2013 et en supposant qu&rsquo;ils ne soient pas majoritairement des descendants de convertis \u2013, en faire un \u00ab\u00a0droit\u00a0\u00bb d&rsquo;envahir et de coloniser le territoire et d&rsquo;en expulser les habitants autochtones est d\u00e9nu\u00e9 de fondement moral ou juridique. Apr\u00e8s tout, les descendants blancs d&rsquo;Am\u00e9rique, d&rsquo;Australie, de Nouvelle-Z\u00e9lande et d&rsquo;Afrique du Sud entretiennent des liens ancestraux authentiques avec l&rsquo;Europe, mais cela ne leur conf\u00e8re aucun droit de la reconqu\u00e9rir et de la recoloniser. De m\u00eame, la domination romaine sur la Grande-Bretagne ne conf\u00e8re pas aux Italiens d&rsquo;aujourd&rsquo;hui le droit de la revendiquer.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Le vol par le sionisme de l&rsquo;h\u00e9ritage des anciens H\u00e9breux palestiniens, les pr\u00e9sentant comme les seuls anc\u00eatres des Juifs europ\u00e9ens, a \u00e9t\u00e9 d\u00e9lib\u00e9r\u00e9ment con\u00e7u pour d\u00e9tacher les Palestiniens de leur propre h\u00e9ritage h\u00e9breu.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Alors que les \u00c9gyptiens, les Jordaniens, les Libanais et les Irakiens peuvent ais\u00e9ment faire remonter leur histoire nationale aux Pharaons, aux Nabat\u00e9ens, aux Ph\u00e9niciens et aux Babyloniens sans contestation, les Palestiniens se voient interdire tout lien souverain avec l&rsquo;h\u00e9ritage antique de la Palestine depuis qu&rsquo;une vague de colons juifs europ\u00e9ens a choisi de s&rsquo;approprier cette histoire.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Par cons\u00e9quent, m\u00eame si les Palestiniens revendiquent l\u00e9gitimement leur descendance des Canan\u00e9ens et des anciens H\u00e9breux, les sionistes leur interdisent cat\u00e9goriquement d&rsquo;int\u00e9grer la moindre racine palestinienne ancienne \u00e0 leur lign\u00e9e. Depuis ses d\u00e9buts, le sionisme s&rsquo;appuie sur des arguments ridicules et irr\u00e9alistes qui s&rsquo;effondrent sous le regard des colonis\u00e9s. Depuis plus de 125 ans, les Palestiniens d\u00e9mant\u00e8lent syst\u00e9matiquement ces mythes, mais la logique m\u00eame de leurs r\u00e9futations n&rsquo;a pas r\u00e9ussi \u00e0 dissuader les soutiens coloniaux d&rsquo;Isra\u00ebl dans l&rsquo;Occident imp\u00e9rial.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">L&rsquo;attrait du r\u00e9cit trompeur du sionisme d\u00e9coule de l&rsquo;attachement du christianisme europ\u00e9en aux mythes bibliques reformul\u00e9s et aux cadres racistes \u2013 l&rsquo;id\u00e9ologie m\u00eame qui a cautionn\u00e9 non seulement le colonialisme de peuplement sioniste, mais aussi la soumission brutale des Am\u00e9riques, l&rsquo;asservissement des Africains et l&#8217;emprise durable de l&rsquo;h\u00e9g\u00e9monie occidentale dans le monde entier.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Aucun argument sioniste ne se distingue de ceux des autres colons europ\u00e9ens. Cela explique pourquoi la pouss\u00e9e d&rsquo;Isra\u00ebl vers un \u00ab Grand Isra\u00ebl \u00bb \u00e0 l&rsquo;\u00e9poque actuelle ne marque pas une rupture avec la tradition mais son apog\u00e9e : le chapitre le plus audacieux d&rsquo;une saga coloniale de peuplement qui s&rsquo;est perp\u00e9tuellement envelopp\u00e9e de r\u00e9cits de retour mythique, de statut d&rsquo;indig\u00e9n\u00e9it\u00e9 fabriqu\u00e9 et d&rsquo;une pr\u00e9tendue promesse divine.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\"><strong>Bibliographie<\/strong> :<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-The Times of Israel. (2025, August 12). <em><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.timesofisrael.com\/liveblog_entry\/netanyahu-says-hes-on-a-historic-and-spiritual-mission-endorses-vision-of-greater-israel\/\">Netanyahu says he\u2019s on a \u201chistoric and spiritual mission,\u201d also feels a connection to vision of Greater Israel<\/a><\/span>.<\/em> The Times of Israel.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-Shah, T. (2025, August 15). <\/span><\/span><\/span><span style=\"font-family: Arial, sans-serif; color: #ff0000;\"><span style=\"font-size: medium;\"><em><a style=\"color: #ff0000;\" href=\"https:\/\/www.middleeasteye.net\/explainers\/what-greater-israel\">What is &lsquo;Greater Israel&rsquo;?<\/a><\/em><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">. Middle East Eye.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-Berg, R. (2025, August 8). <span style=\"color: #ff0000;\"><em>Israel approves plan to take control of Gaza City, signalling major escalation<\/em><\/span>. BBC News.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-Uddin, ayhan, &amp; Masarwa, L. (2025, August 20). <span style=\"color: #ff0000;\"><em><a style=\"color: #ff0000;\" href=\"https:\/\/www.middleeasteye.net\/news\/israel-approves-e1-settlement-smotrich-says-palestinian-state-being-erased\">Israel approves E1 settlement to &lsquo;erase&rsquo; Palestinian state with &lsquo;actions not slogans.&rsquo;<\/a> <\/em><\/span>Middle East Eye.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-Abou Shhadeh, A. (2024, October 3). <em><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.middleeasteye.net\/opinion\/israel-arab-countries-stop-appeasing-violent-expansionist\">Arab countries must stop appeasing a violent expansionist Israel<\/a><\/span><\/em>. Middle East Eye.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-Amnesty International. (2025a, July 3). <span style=\"color: #ff0000;\"><em><a style=\"color: #ff0000;\" href=\"https:\/\/www.amnesty.org\/en\/latest\/news\/2025\/07\/gaza-evidence-points-to-israels-continued-use-of-starvation-to-inflict-genocide-against-palestinians\/\">Gaza: Evidence points to Israel\u2019s continued use of starvation to inflict genocide against Palestinians<\/a><\/em><\/span>. Amnesty International.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-Rothwell, D. (2025, June 8). <span style=\"color: #ff0000;\"><em><a style=\"color: #ff0000;\" href=\"https:\/\/theconversation.com\/can-israel-still-claim-self-defence-to-justify-its-gaza-war-257822\">Can Israel still claim self-defence to justify its Gaza war?<\/a><\/em><\/span>. The Conversation.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-Lesch, A. M. (2011, October 3). <em>Zionism and its impact<\/em>. WRMEA.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-Massad, J. (2006). <em>The Persistence of the Palestinian Question: Essays on Zionism and the Palestinians.<\/em> United Kingdom: Taylor &amp; Francis.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-Khalidi, R. (2020). <em>The hundred years&rsquo; war on Palestine: A history of settler colonialism and resistance, 1917\u20132017<\/em>. Metropolitan Books.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-Kakel, C. (2013).<em> The Holocaust as Colonial Genocide: Hitler&rsquo;s &lsquo;Indian Wars&rsquo; in the &lsquo;Wild East&rsquo;<\/em>. United Kingdom: Palgrave Macmillan.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-Whaley, J. (2014). <span style=\"color: #ff0000;\"><em>\u2018Hier existiert noch das alte heilige deutsche Reich\u2019: The Legacy of the Holy Roman Empire and the Unity of Germany<\/em><\/span>. Publications of the English Goethe Society, 83(1), 1\u201321.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-University of Oxford. (2018, September 17). <span style=\"color: #ff0000;\"><em>How did the Christian Middle East become predominantly Muslim?<\/em><\/span>. University of Oxford.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-Donner, F. M. (2014).<em> The Early Islamic Conquests<\/em>. United States: Princeton University Press.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">&#8211;<em><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.palestineremembered.com\/Acre\/Famous-Zionist-Quotes\/Story638.html\">David Ben-Gurion-A Brief Biography &amp; Quotes.<\/a><\/span><\/em> (n.d.). Palestine Remembered.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-Cleveland, W. L. (1972). <em>The making of an Arab nationalist: Ottomanism and Arabism in the life and thought of Sati&rsquo; al-Husri<\/em>. Princeton University Press.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-HERLIHY, P. (1977). <span style=\"color: #ff0000;\"><em>The Ethnic Composition of the City of Odessa in the Nineteenth Century<\/em><\/span>. Harvard Ukrainian Studies, 1(1), 53\u201378.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">-Sand, S. (2020). <em>The Invention of the Jewish People<\/em>. United Kingdom: Verso Books.<\/span><\/span><\/span><\/p>\n<pre><em><strong><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Article original en anglais sur le <a href=\"https:\/\/x.com\/HandalaFreedom\/status\/1976585365386363182?t=f5fsAsZVhHpr1zN4BChqAQ&amp;s=09\">compte X de Handala<\/a>\u00a0\/ Traduction MR<\/span><\/span><\/span><\/strong><\/em><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Handala, 10 octobre 2025. Le 12 ao\u00fbt 2025, le Premier ministre isra\u00e9lien Benjamin Netanyahou (Benjamin Mileikowsky) a publiquement soutenu le projet de \u00ab\u00a0Grand Isra\u00ebl\u00a0\u00bb, d\u00e9clarant dans une interview \u00e0 i24 <a class=\"more-link\" href=\"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/\">Lire la suite &rarr;<\/a><\/p>\n","protected":false},"author":3,"featured_media":24175,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,2],"tags":[158,58,82],"class_list":["post-24171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analyses","category-articles","tag-colonialisme-de-peuplement","tag-histoire","tag-propagande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Grand Isra\u00ebl pour les Nuls - International Solidarity Movement - ISM-France<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Grand Isra\u00ebl pour les Nuls - International Solidarity Movement - ISM-France\" \/>\n<meta property=\"og:description\" content=\"Handala, 10 octobre 2025. Le 12 ao\u00fbt 2025, le Premier ministre isra\u00e9lien Benjamin Netanyahou (Benjamin Mileikowsky) a publiquement soutenu le projet de \u00ab\u00a0Grand Isra\u00ebl\u00a0\u00bb, d\u00e9clarant dans une interview \u00e0 i24 Lire la suite &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/\" \/>\n<meta property=\"og:site_name\" content=\"International Solidarity Movement - ISM-France\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-11T08:04:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ismfrance.org\/wp-content\/uploads\/2025\/10\/greaterisrael.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mru_01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ISMFRANCE\" \/>\n<meta name=\"twitter:site\" content=\"@ISMFRANCE\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"mru_01\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ismfrance.org\\\/index.php\\\/2025\\\/10\\\/11\\\/le-grand-israel-pour-les-nuls\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ismfrance.org\\\/index.php\\\/2025\\\/10\\\/11\\\/le-grand-israel-pour-les-nuls\\\/\"},\"author\":{\"name\":\"mru_01\",\"@id\":\"https:\\\/\\\/ismfrance.org\\\/#\\\/schema\\\/person\\\/3c411eb72adfaae19c0dca1f41fae01d\"},\"headline\":\"Le Grand Isra\u00ebl pour les Nuls\",\"datePublished\":\"2025-10-11T08:04:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ismfrance.org\\\/index.php\\\/2025\\\/10\\\/11\\\/le-grand-israel-pour-les-nuls\\\/\"},\"wordCount\":3341,\"publisher\":{\"@id\":\"https:\\\/\\\/ismfrance.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ismfrance.org\\\/index.php\\\/2025\\\/10\\\/11\\\/le-grand-israel-pour-les-nuls\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ismfrance.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/greaterisrael.jpg\",\"keywords\":[\"Colonialisme de peuplement\",\"Histoire\",\"Propagande\"],\"articleSection\":[\"Analyses\",\"Articles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ismfrance.org\\\/index.php\\\/2025\\\/10\\\/11\\\/le-grand-israel-pour-les-nuls\\\/\",\"url\":\"https:\\\/\\\/ismfrance.org\\\/index.php\\\/2025\\\/10\\\/11\\\/le-grand-israel-pour-les-nuls\\\/\",\"name\":\"Le Grand Isra\u00ebl pour les Nuls - International Solidarity Movement - ISM-France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ismfrance.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ismfrance.org\\\/index.php\\\/2025\\\/10\\\/11\\\/le-grand-israel-pour-les-nuls\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ismfrance.org\\\/index.php\\\/2025\\\/10\\\/11\\\/le-grand-israel-pour-les-nuls\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ismfrance.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/greaterisrael.jpg\",\"datePublished\":\"2025-10-11T08:04:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ismfrance.org\\\/index.php\\\/2025\\\/10\\\/11\\\/le-grand-israel-pour-les-nuls\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ismfrance.org\\\/index.php\\\/2025\\\/10\\\/11\\\/le-grand-israel-pour-les-nuls\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ismfrance.org\\\/index.php\\\/2025\\\/10\\\/11\\\/le-grand-israel-pour-les-nuls\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ismfrance.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/greaterisrael.jpg\",\"contentUrl\":\"https:\\\/\\\/ismfrance.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/greaterisrael.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ismfrance.org\\\/index.php\\\/2025\\\/10\\\/11\\\/le-grand-israel-pour-les-nuls\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ismfrance.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Grand Isra\u00ebl pour les Nuls\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ismfrance.org\\\/#website\",\"url\":\"https:\\\/\\\/ismfrance.org\\\/\",\"name\":\"ISM Palestine France\",\"description\":\"Soutien aux luttes de lib\u00e9ration du peuple palestinien\",\"publisher\":{\"@id\":\"https:\\\/\\\/ismfrance.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ismfrance.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ismfrance.org\\\/#organization\",\"name\":\"International Solidarity Movement\",\"url\":\"https:\\\/\\\/ismfrance.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ismfrance.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ismfrance.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/00.png\",\"contentUrl\":\"https:\\\/\\\/ismfrance.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/00.png\",\"width\":400,\"height\":400,\"caption\":\"International Solidarity Movement\"},\"image\":{\"@id\":\"https:\\\/\\\/ismfrance.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/ISMFRANCE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ismfrance.org\\\/#\\\/schema\\\/person\\\/3c411eb72adfaae19c0dca1f41fae01d\",\"name\":\"mru_01\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a0be343b445d2ccc79e87444a294fad2b232e90d2051d0e3cc219e1ecd6a330?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a0be343b445d2ccc79e87444a294fad2b232e90d2051d0e3cc219e1ecd6a330?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a0be343b445d2ccc79e87444a294fad2b232e90d2051d0e3cc219e1ecd6a330?s=96&d=mm&r=g\",\"caption\":\"mru_01\"},\"url\":\"https:\\\/\\\/ismfrance.org\\\/index.php\\\/author\\\/admin02\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Grand Isra\u00ebl pour les Nuls - International Solidarity Movement - ISM-France","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Grand Isra\u00ebl pour les Nuls - International Solidarity Movement - ISM-France","og_description":"Handala, 10 octobre 2025. Le 12 ao\u00fbt 2025, le Premier ministre isra\u00e9lien Benjamin Netanyahou (Benjamin Mileikowsky) a publiquement soutenu le projet de \u00ab\u00a0Grand Isra\u00ebl\u00a0\u00bb, d\u00e9clarant dans une interview \u00e0 i24 Lire la suite &rarr;","og_url":"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/","og_site_name":"International Solidarity Movement - ISM-France","article_published_time":"2025-10-11T08:04:55+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/ismfrance.org\/wp-content\/uploads\/2025\/10\/greaterisrael.jpg","type":"image\/jpeg"}],"author":"mru_01","twitter_card":"summary_large_image","twitter_creator":"@ISMFRANCE","twitter_site":"@ISMFRANCE","twitter_misc":{"\u00c9crit par":"mru_01","Dur\u00e9e de lecture estim\u00e9e":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/#article","isPartOf":{"@id":"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/"},"author":{"name":"mru_01","@id":"https:\/\/ismfrance.org\/#\/schema\/person\/3c411eb72adfaae19c0dca1f41fae01d"},"headline":"Le Grand Isra\u00ebl pour les Nuls","datePublished":"2025-10-11T08:04:55+00:00","mainEntityOfPage":{"@id":"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/"},"wordCount":3341,"publisher":{"@id":"https:\/\/ismfrance.org\/#organization"},"image":{"@id":"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/#primaryimage"},"thumbnailUrl":"https:\/\/ismfrance.org\/wp-content\/uploads\/2025\/10\/greaterisrael.jpg","keywords":["Colonialisme de peuplement","Histoire","Propagande"],"articleSection":["Analyses","Articles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/","url":"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/","name":"Le Grand Isra\u00ebl pour les Nuls - International Solidarity Movement - ISM-France","isPartOf":{"@id":"https:\/\/ismfrance.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/#primaryimage"},"image":{"@id":"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/#primaryimage"},"thumbnailUrl":"https:\/\/ismfrance.org\/wp-content\/uploads\/2025\/10\/greaterisrael.jpg","datePublished":"2025-10-11T08:04:55+00:00","breadcrumb":{"@id":"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/#primaryimage","url":"https:\/\/ismfrance.org\/wp-content\/uploads\/2025\/10\/greaterisrael.jpg","contentUrl":"https:\/\/ismfrance.org\/wp-content\/uploads\/2025\/10\/greaterisrael.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/ismfrance.org\/index.php\/2025\/10\/11\/le-grand-israel-pour-les-nuls\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ismfrance.org\/"},{"@type":"ListItem","position":2,"name":"Le Grand Isra\u00ebl pour les Nuls"}]},{"@type":"WebSite","@id":"https:\/\/ismfrance.org\/#website","url":"https:\/\/ismfrance.org\/","name":"ISM Palestine France","description":"Soutien aux luttes de lib\u00e9ration du peuple palestinien","publisher":{"@id":"https:\/\/ismfrance.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ismfrance.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ismfrance.org\/#organization","name":"International Solidarity Movement","url":"https:\/\/ismfrance.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ismfrance.org\/#\/schema\/logo\/image\/","url":"https:\/\/ismfrance.org\/wp-content\/uploads\/2020\/12\/00.png","contentUrl":"https:\/\/ismfrance.org\/wp-content\/uploads\/2020\/12\/00.png","width":400,"height":400,"caption":"International Solidarity Movement"},"image":{"@id":"https:\/\/ismfrance.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/ISMFRANCE"]},{"@type":"Person","@id":"https:\/\/ismfrance.org\/#\/schema\/person\/3c411eb72adfaae19c0dca1f41fae01d","name":"mru_01","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3a0be343b445d2ccc79e87444a294fad2b232e90d2051d0e3cc219e1ecd6a330?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3a0be343b445d2ccc79e87444a294fad2b232e90d2051d0e3cc219e1ecd6a330?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3a0be343b445d2ccc79e87444a294fad2b232e90d2051d0e3cc219e1ecd6a330?s=96&d=mm&r=g","caption":"mru_01"},"url":"https:\/\/ismfrance.org\/index.php\/author\/admin02\/"}]}},"_links":{"self":[{"href":"https:\/\/ismfrance.org\/index.php\/wp-json\/wp\/v2\/posts\/24171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismfrance.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismfrance.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismfrance.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ismfrance.org\/index.php\/wp-json\/wp\/v2\/comments?post=24171"}],"version-history":[{"count":0,"href":"https:\/\/ismfrance.org\/index.php\/wp-json\/wp\/v2\/posts\/24171\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismfrance.org\/index.php\/wp-json\/wp\/v2\/media\/24175"}],"wp:attachment":[{"href":"https:\/\/ismfrance.org\/index.php\/wp-json\/wp\/v2\/media?parent=24171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismfrance.org\/index.php\/wp-json\/wp\/v2\/categories?post=24171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismfrance.org\/index.php\/wp-json\/wp\/v2\/tags?post=24171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}